{"id":142526,"date":"2026-06-09T12:08:33","date_gmt":"2026-06-09T09:08:33","guid":{"rendered":"https:\/\/onlinestandart.com\/standard\/iec-60601-1-22014\/"},"modified":"2026-06-09T12:08:57","modified_gmt":"2026-06-09T09:08:57","slug":"iec-60601-1-22014","status":"publish","type":"product","link":"https:\/\/onlinestandart.com\/en\/standard\/iec-60601-1-22014\/","title":{"rendered":"IEC 60601-1-2:2014"},"content":{"rendered":"<p>Medical electrical equipment &#8211; Part 1-2: General requirements for basic safety and essential performance &#8211; Collateral Standard: Electromagnetic disturbances &#8211; Requirements and tests<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medical electrical equipment &#8211; Part 1-2: General requirements for basic safety and essential performance &#8211; Collateral Standard: Electromagnetic disturbances &#8211; Requirements and tests<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":""},"product_brand":[],"product_cat":[173],"product_tag":[],"class_list":["post-142526","product","type-product","status-publish","product_cat-iec","first","instock","purchasable","product-type-simple","entry","content-bg","loop-entry"],"taxonomy_info":{"product_cat":[{"value":173,"label":"IEC"}]},"featured_image_src_large":false,"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/product\/142526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/media?parent=142526"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/product_brand?post=142526"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/product_cat?post=142526"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/onlinestandart.com\/en\/wp-json\/wp\/v2\/product_tag?post=142526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}